{"id":382,"count":1,"description":"","link":"https:\/\/kyanoe.com\/en\/tag\/%e4%b8%ad%e5%9b%bd%e5%8b%9d%e5%b1%b1\/","name":"\u4e2d\u56fd\u52dd\u5c71","slug":"%e4%b8%ad%e5%9b%bd%e5%8b%9d%e5%b1%b1","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/kyanoe.com\/wp-json\/wp\/v2\/tags\/382","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kyanoe.com\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/kyanoe.com\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/kyanoe.com\/wp-json\/wp\/v2\/posts?tags=382"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}